{"id":172,"date":"2024-10-08T11:08:22","date_gmt":"2024-10-08T11:08:22","guid":{"rendered":"https:\/\/atemschwung.ch\/aktuell\/?p=172"},"modified":"2024-10-08T11:08:22","modified_gmt":"2024-10-08T11:08:22","slug":"oder-ist-es-das-licht-das-ruft","status":"publish","type":"post","link":"https:\/\/atemschwung.ch\/aktuell\/oder-ist-es-das-licht-das-ruft\/","title":{"rendered":"Oder ist es das Licht das ruft ?"},"content":{"rendered":"<p class=\"western\">Oder ist es das Licht, das ruft ?<\/p>\n<p class=\"western\">Im letzten Text habe ich gesagt, dass wir alle Traumas in uns tragen und dass es darum geht diese anzunehmen und aufzul\u00f6sen, so dass die Lebensenergie freier fliessen kann.<\/p>\n<p class=\"western\">Ein Trauma ist eine Wunde, die \u2039eingepackt\u203a wurde, weil wir in dem Moment, als sie entstand, meinten, dass das volle F\u00fchlen davon zu viel f\u00fcr uns w\u00e4re. So haben wir sie \u2039eingepackt\u203a, damit sie dem Ganzen nicht mehr schaden kann. Und irgendwann kommt der Zeitpunkt, in dem wir es wagen, diese Wunden wieder \u2039auszupacken\u203a, damit sie ganz ausheilen k\u00f6nnen. Entweder weil diese Wunde im Verborgenen geeitert hat, sprich wir erleben Krankheiten oder weil sie br\u00fcllt und emotionales oder mentales Unwohlsein verursacht.<\/p>\n<p class=\"western\">Halleluja! Was f\u00fcr ein Moment voller Gnade. Zeit f\u00fcr Befreiung, Zeit f\u00fcr Erweiterung, Zeit f\u00fcr liebevoll zugewandte Sanftheit.<\/p>\n<p class=\"western\">Die Tage werden nun wieder k\u00fcrzer, die \u00e4ussere Dunkelheit nimmt mehr Raumzeit ein. Es zieht uns nach innen, an den Herd, ans Feuer, aufs Sofa mit den vielen Kissen, eine Tasse mit warmem Tee in der Hand. Wir erlauben uns sanftes Wohlsein voller Nichtstun. Dies ist eine wunderbare Haltung, in der wir uns unseren Wunden zuwenden k\u00f6nnen. Oft sind diese Wunden nicht einmal pers\u00f6nlich, wir haben sie mitgenommen aus unserer Ahnenreihe, um sie irgendwann f\u00fcr uns und alle unsere Ahnen zu befreien. Das kann uns helfen, weil es so leichter ist, einen kleinen Abstand zu wahren. Nur genau so viel Abstand, dass wir uns als bedingungslos liebende Grossmutter erleben k\u00f6nnen, die in unendlicher Geduld, einfach da ist und der Wunde zuh\u00f6rt, ihr zuschaut, wie sie sich ausdr\u00fccken will und sie mit ihrer bedingungslosen Anerkennung und Liebe sanft w\u00e4rmt. Sie ist eine kosmische Grossmutter, die in uns allen, Frauen und M\u00e4nnern, wohnt.<\/p>\n<p class=\"western\">In diesem warmen Licht der liebenden Zuwendung, kann die Wunde langsam heilen. Sie hat alle Zeit der Welt daf\u00fcr. Und du trinkst noch einen Schluck deines Tees, f\u00fchlst, wie seine W\u00e4rme und sein Aroma sich in dir ausbreiten, Wohlwollen, Wohlf\u00fchlen. Du \u00fcberl\u00e4sst dich dem Willen, der nicht gewollt werden kann, Wohl zu sein. Und dann geschieht ein Wunder: du erkennst im Schatten ein Licht, in der Wunde ein Geschenk. Zuerst erahnst du es nur, irgendwie f\u00fchlst du dich ganzer, wie wenn sich etwas in dir erinnert h\u00e4tte.<\/p>\n<p class=\"western\">Heilen ist ganz werden, heilen ist Integrieren, heilen heisst immer mehr in unser Potenzial hinein zu wachsen.\u00a0\u00a0\u00a0\u00a0\u00a0 Nun gilt unsere Aufmerksamkeit auch diesem neuen Licht und wir erforschen es mit der gleichen wohlwollenden Zuwendung. So w\u00e4chst das Licht und das Geschenk wird klarer. Es ist eine Reise ins Unbekannte oder besser ins Unbewusste, gekannt haben wir es schon immer, das, was da in seiner ganzen Bandbreite von Schmerz bis Ekstase in uns lebt.<\/p>\n<p class=\"western\">Ich w\u00fcnsche uns allen diesen Mut. Mut eine Pause einzulegen, Mut da zu sein mit allem was sich zeigt, Mut, die Geschenke anzunehmen und zu leben. F\u00fcr uns selbst, f\u00fcr alle unsere Ahnen, f\u00fcr alle die nach uns kommen, f\u00fcr das grosse Ganze.<\/p>\n<p class=\"western\" align=\"left\">Und wenn du einmal eine \u00e4ussere Grossmutter brauchst, die mit dir eine Tasse Tee trinkt, kannst du mir schreiben an: silvia@atemschwung.ch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oder ist es das Licht, das ruft ? Im letzten Text habe ich gesagt, dass wir alle Traumas in uns tragen und dass es darum geht diese anzunehmen und aufzul\u00f6sen, so dass die Lebensenergie freier fliessen kann. Ein Trauma ist eine Wunde, die \u2039eingepackt\u203a wurde, weil wir in dem Moment, als sie entstand, meinten, dass&hellip;&nbsp;<a href=\"https:\/\/atemschwung.ch\/aktuell\/oder-ist-es-das-licht-das-ruft\/\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Oder ist es das Licht das ruft ?<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":1,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"predecessor-version":[{"id":173,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/posts\/172\/revisions\/173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/media\/178"}],"wp:attachment":[{"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}