{"id":104,"date":"2021-10-24T11:18:42","date_gmt":"2021-10-24T11:18:42","guid":{"rendered":"https:\/\/atemschwung.ch\/aktuell\/?p=104"},"modified":"2021-10-24T11:19:49","modified_gmt":"2021-10-24T11:19:49","slug":"lust-auf-selbstverantwortung","status":"publish","type":"post","link":"https:\/\/atemschwung.ch\/aktuell\/lust-auf-selbstverantwortung\/","title":{"rendered":"Lust auf Selbstverantwortung"},"content":{"rendered":"<p class=\"western\" align=\"left\">Ich bin sozial; irgendwie war ich das schon immer.<\/p>\n<p class=\"western\" align=\"left\">Jeder Mensch weckt sofort mein Interesse und kreative M\u00f6glichkeiten das Gemeinsame zu zelebrieren er\u00f6ffnen sich mir nat\u00fcrlicherweise.<\/p>\n<p class=\"western\" align=\"left\">So kam es, dass ich oft Menschen um mich herum hatte, gemeinsame Aktivit\u00e4ten organisierte und f\u00fcr jedes \u00abhe kannst du mal..\u00bb abrufbar war.<\/p>\n<p class=\"western\" align=\"left\">Irgendwann habe ich gemerkt, dass ich m\u00fcde werde, dass mir der Ausgleich fehlt. Aber wie das so ist mit Rollen im Leben, es ist nicht immer leicht, sie abzulegen. Aus einem selbst heraus nicht; wer bin ich dann? Aber auch die Umgebung quittiert es oft mit Unverst\u00e4ndnis oder Widerstand.<\/p>\n<p class=\"western\" align=\"left\">Wer weiss, vielleicht hat auch mein Wunsch nach erneuerndem Ausgleich mitgeholfen, den Krebs zu formen, der mir endg\u00fcltig die innere Berechtigung gab, mich zur\u00fcck zu ziehen. ; )<\/p>\n<p class=\"western\" align=\"left\">Nun bin ich hier, in der Stille und Weite der Vogesen und Balance wird hergestellt. Als Studentin der Lebensenergie \u00fcbe ich viel Qi Gong und konversiere mit der Natur und den unsichtbaren Kr\u00e4ften.<\/p>\n<p class=\"western\" align=\"left\">Es er\u00f6ffnet sich mir eine lustvollen Selbstverantwortung im t\u00e4glichen Erleben.<\/p>\n<p class=\"western\" align=\"left\">Qi Gong ist eine lebendige, effektive Art und Weise Selbstverantwortung f\u00fcr mich, meine Gesundheit und mein Wohlsein zu \u00fcbernehmen.<\/p>\n<p class=\"western\" align=\"left\">Ohne in Geschichten einzutauchen, fordert es mich auf, direkt im Moment, wach zu sein und das nat\u00fcrliche Potenzial immer und immer wieder zu erforschen. Die Klarheit des direkt Erlebten ersetzt Konzepte und das Wachsen der Kraft, der Durchl\u00e4ssigkeit und der inneren Ruhe verifiziert die Wirksamkeit.<\/p>\n<p class=\"western\" align=\"left\">Wie weit magst du gehen in der Auseinandersetzung mit Selbstverantwortung?<\/p>\n<p class=\"western\" align=\"left\">Was traust du dir selber zu und was gibst du an wen ab?<\/p>\n<p class=\"western\" align=\"left\">Wenn du Lust hast, dich auf das Erlebnis Qi Gong einzulassen, hast du hier die M\u00f6glichkeit:<\/p>\n<p>Zwei Jahreskurse in Qi Gong laufen am Lehrinstitut LIKA in Stilli www.lika.ch<br \/>\nund Ihr k\u00f6nnt mich mieten:<\/p>\n<ul>\n<li>f\u00fcr Qi Gong, allgemein oder zu einem spezifischen Thema,<\/li>\n<li>f\u00fcr Information und Erleben der 5 Elemente, in Ern\u00e4hrung, Bewegung und Achtsamkeit<\/li>\n<li>wie der Atem als Weg und Verbindung zu und Anker in deiner inneren Wahrheit eingesetzt werden kann<\/li>\n<li>wie wir auch noch mit Diagnosen wie Krebs, MS etc. umgehen k\u00f6nnten. Du organisierst einen Ort und interessierte Teilnehmer und ich komme, unterrichte, inspiriere, leite an.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ich bin sozial; irgendwie war ich das schon immer. Jeder Mensch weckt sofort mein Interesse und kreative M\u00f6glichkeiten das Gemeinsame zu zelebrieren er\u00f6ffnen sich mir nat\u00fcrlicherweise. So kam es, dass ich oft Menschen um mich herum hatte, gemeinsame Aktivit\u00e4ten organisierte und f\u00fcr jedes \u00abhe kannst du mal..\u00bb abrufbar war. Irgendwann habe ich gemerkt, dass ich&hellip;&nbsp;<a href=\"https:\/\/atemschwung.ch\/aktuell\/lust-auf-selbstverantwortung\/\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Lust auf Selbstverantwortung<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":105,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/posts\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":3,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/posts\/104\/revisions"}],"predecessor-version":[{"id":110,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/posts\/104\/revisions\/110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/media\/105"}],"wp:attachment":[{"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/media?parent=104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/categories?post=104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atemschwung.ch\/aktuell\/wp-json\/wp\/v2\/tags?post=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}